{"id":14754,"date":"2026-06-10T10:18:40","date_gmt":"2026-06-10T08:18:40","guid":{"rendered":"https:\/\/fisheries.groupcls.com\/?p=14754"},"modified":"2026-06-16T14:25:39","modified_gmt":"2026-06-16T12:25:39","slug":"cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques","status":"publish","type":"post","link":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/","title":{"rendered":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable : une reconnaissance internationale au service de la science oc\u00e9anique"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-14742\" src=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Endorsed-by-the-UN-Decade-of-Ocean-Science-for-Sustainable-Development.png\" alt=\"Endorsed by the UN Decade of Ocean Science for Sustainable Development\" width=\"300\" height=\"300\" srcset=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Endorsed-by-the-UN-Decade-of-Ocean-Science-for-Sustainable-Development.png 880w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Endorsed-by-the-UN-Decade-of-Ocean-Science-for-Sustainable-Development-150x150.png 150w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Endorsed-by-the-UN-Decade-of-Ocean-Science-for-Sustainable-Development-768x768.png 768w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Endorsed-by-the-UN-Decade-of-Ocean-Science-for-Sustainable-Development-86x86.png 86w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Endorsed-by-the-UN-Decade-of-Ocean-Science-for-Sustainable-Development-280x280.png 280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">Comprendre et pr\u00e9server l\u2019oc\u00e9an est devenu un enjeu scientifique, environnemental et soci\u00e9tal majeur. Dans ce contexte, la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable (2021-2030) mobilise la communaut\u00e9 internationale autour d\u2019un objectif commun : d\u00e9velopper \u00ab la science dont nous avons besoin pour l\u2019oc\u00e9an que nous voulons \u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>CLS est fier d\u2019annoncer que son initiative de mod\u00e9lisation mondiale du zooplancton et du micronecton a \u00e9t\u00e9 officiellement reconnue comme projet de la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ces organismes, qui constituent les niveaux trophiques inf\u00e9rieurs et interm\u00e9diaires, sont des composantes essentielles des \u00e9cosyst\u00e8mes marins. Ils assurent le lien entre les producteurs primaires et les pr\u00e9dateurs sup\u00e9rieurs, parmi lesquels figurent des esp\u00e8ces embl\u00e9matiques et d\u2019int\u00e9r\u00eat commercial. Ils effectuent \u00e9galement des migrations verticales, faisant d\u2019eux des acteurs cl\u00e9s du transport et de la s\u00e9questration du carbone depuis les couches de surface vers l\u2019oc\u00e9an profond, un processus d\u2019une importance majeure dans le contexte du changement climatique.<\/p>\n<p style=\"text-align: justify;\">Les <a href=\"https:\/\/oceandecade.org\/fr\/challenges\/\" target=\"_blank\" rel=\"noopener\">d\u00e9fis de la D\u00e9cennie de l\u2019Oc\u00e9an<\/a> visent \u00e0 mobiliser la communaut\u00e9 internationale autour des enjeux oc\u00e9aniques les plus urgents, \u00e0 favoriser la coop\u00e9ration scientifique et \u00e0 contribuer \u00e0 l\u2019atteinte des Objectifs de d\u00e9veloppement durable des Nations Unies \u00e0 l\u2019horizon 2030.<\/p>\n<p>[\/vc_column_text][vc_btn title=\u00a0\u00bbEn savoir plus sur la vision 2030&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Foceandecade.org%2Ffr%2Fpublications%2Focean-decade-vision-2030-white-papers%2F|target:_blank|\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">Cette reconnaissance a \u00e9t\u00e9 accord\u00e9e par la <a href=\"https:\/\/www.ioc.unesco.org\/fr\" target=\"_blank\" rel=\"noopener\">Commission oc\u00e9anographique intergouvernementale (COI) de l\u2019UNESCO<\/a>, avec le soutien de l\u2019<a href=\"https:\/\/oceandecade.org\/fr\/decade-collaborative-centres\/\" target=\"_blank\" rel=\"noopener\">\u00e9quipe de coordination de la D\u00e9cennie de l\u2019Oc\u00e9an<\/a>. Elle souligne l\u2019importance du renforcement des connaissances scientifiques et de la coop\u00e9ration internationale pour r\u00e9pondre aux grands d\u00e9fis li\u00e9s \u00e0 la compr\u00e9hension, \u00e0 la protection et \u00e0 la gestion durable de l\u2019oc\u00e9an.<\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h2>Un projet scientifique international port\u00e9 par CLS : \u00ab Global Ocean Low and Mid Trophic Levels Biomass \u00bb<\/h2>\n<p style=\"text-align: justify;\">Depuis plusieurs d\u00e9cennies, CLS d\u00e9veloppe des solutions innovantes fond\u00e9es sur les donn\u00e9es satellitaires et les technologies d\u2019observation de la Terre afin de mieux comprendre la dynamique oc\u00e9anique et de soutenir la gestion durable des \u00e9cosyst\u00e8mes marins.<\/p>\n<figure id=\"attachment_14748\" aria-describedby=\"caption-attachment-14748\" style=\"width: 400px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14748\" src=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Global-Distribution-of-Non-Migrant-Epipelagic-Micronekton-Biomass.jpg\" alt=\"Global Distribution of Non-Migrant Epipelagic Micronekton Biomass\" width=\"400\" height=\"221\" srcset=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Global-Distribution-of-Non-Migrant-Epipelagic-Micronekton-Biomass.jpg 800w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Global-Distribution-of-Non-Migrant-Epipelagic-Micronekton-Biomass-768x423.jpg 768w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Global-Distribution-of-Non-Migrant-Epipelagic-Micronekton-Biomass-795x440.jpg 795w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-14748\" class=\"wp-caption-text\">Source : sorties du mod\u00e8le SEAPODYM repr\u00e9sentant la distribution de la biomasse du micronecton \u00e9pip\u00e9lagique non migrant ; traitement des donn\u00e9es et visualisation r\u00e9alis\u00e9s par Laur\u00e8ne Merillet, mod\u00e9lisatrice des \u00e9cosyst\u00e8mes marins au sein du groupe CLS.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Le mod\u00e8le SEAPODYM est d\u00e9velopp\u00e9 depuis vingt ans en collaboration avec la Communaut\u00e9 du Pacifique (SPC). Il permet de mod\u00e9liser la dynamique spatiale des \u00e9cosyst\u00e8mes p\u00e9lagiques et des cha\u00eenes trophiques marines.<\/p>\n<p style=\"text-align: justify;\">Depuis mi-2019, ce mod\u00e8le est utilis\u00e9 pour produire le jeu de donn\u00e9es \u00ab Global Ocean Low and Mid Trophic Levels Biomass Content Hindcast \u00bb, qui estime \u00e0 l\u2019\u00e9chelle mondiale la biomasse du zooplancton et du micronecton. Ce produit est librement accessible dans le <a href=\"https:\/\/data.marine.copernicus.eu\/product\/GLOBAL_MULTIYEAR_BGC_001_033\/description\" target=\"_blank\" rel=\"noopener\">catalogue du Copernicus Marine Environment Monitoring Service (CMEMS)<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 travers ce projet, CLS r\u00e9affirme son engagement en faveur d\u2019une science ouverte, collaborative et op\u00e9rationnelle au service des scientifiques, des d\u00e9cideurs et des acteurs de l\u2019\u00e9conomie maritime.<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1780673261098{margin-top: 40px !important;margin-bottom: 40px !important;padding-top: 20px !important;padding-right: 20px !important;padding-left: 20px !important;background-color: #F5F7FA !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<figure id=\"attachment_14765\" aria-describedby=\"caption-attachment-14765\" style=\"width: 400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14765\" src=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Micronekton.jpg\" alt=\"Micronekton\" width=\"400\" height=\"267\" srcset=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Micronekton.jpg 800w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Micronekton-768x512.jpg 768w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Micronekton-360x240.jpg 360w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-14765\" class=\"wp-caption-text\">Exemples d\u2019organismes micronektoniques pr\u00e9sent\u00e9s ici : poissons m\u00e9sop\u00e9lagiques, c\u00e9phalopodes, organismes g\u00e9latineux et crustac\u00e9s. Cr\u00e9dit photo : Gildas Roudaut, Institut de Recherche pour le D\u00e9veloppement (IRD), Brest, France. Figure haute r\u00e9solution.<\/figcaption><\/figure>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<figure id=\"attachment_14745\" aria-describedby=\"caption-attachment-14745\" style=\"width: 400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14745\" src=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Zooplancton.jpg\" alt=\"Zooplankton Organisms\" width=\"400\" height=\"267\" srcset=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Zooplancton.jpg 800w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Zooplancton-768x512.jpg 768w, https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Zooplancton-360x240.jpg 360w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-14745\" class=\"wp-caption-text\">Exemples d\u2019organismes zooplanctoniques cl\u00e9s qui soutiennent les r\u00e9seaux trophiques marins<\/figcaption><\/figure>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">Le projet \u00ab Global Ocean Low and Mid Trophic Levels Biomass \u00bb, coordonn\u00e9 par Olivier Titaud, ing\u00e9nieur de recherche en calcul num\u00e9rique chez CLS Group, fait d\u00e9sormais partie de <a href=\"https:\/\/jetzon.org\/news\/three-new-projects-endorsed-ocean-decade-under-jetzon-antics-drift-and-miczoo2\" target=\"_blank\" rel=\"noopener\">JETZON<\/a> (Joint Exploration of the Twilight Zone Ocean Network), un r\u00e9seau scientifique international d\u00e9di\u00e9 \u00e0 l\u2019exploration de la zone m\u00e9sop\u00e9lagique, \u00e9galement connue sous le nom de \u00ab Twilight Zone \u00bb.<\/p>\n<p style=\"text-align: justify;\">Situ\u00e9e entre 200 et 1 000 m\u00e8tres de profondeur, cette couche de l\u2019oc\u00e9an joue un r\u00f4le essentiel dans :<\/p>\n<ul>\n<li>le fonctionnement des r\u00e9seaux trophiques marins ;<\/li>\n<li>les cycles biog\u00e9ochimiques ;<\/li>\n<li>le stockage du carbone et la r\u00e9gulation du climat.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Encore largement m\u00e9connue, cette r\u00e9gion constitue l\u2019une des grandes fronti\u00e8res de la recherche oc\u00e9anographique internationale.<\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb.vc_custom_1781004728434{padding-top: 30px !important;padding-right: 30px !important;padding-bottom: 30px !important;padding-left: 30px !important;background-color: #F5F7FA !important;}\u00a0\u00bb]<\/p>\n<h2>Une mobilisation mondiale pour l\u2019avenir de l\u2019oc\u00e9an port\u00e9e par la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable<\/h2>\n<p style=\"text-align: justify;\">Lanc\u00e9e par les Nations Unies et coordonn\u00e9e par la COI-UNESCO, la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable vise \u00e0 acc\u00e9l\u00e9rer la production et le partage des connaissances scientifiques n\u00e9cessaires \u00e0 une gestion durable de l\u2019oc\u00e9an d\u2019ici 2030.<\/p>\n<p style=\"text-align: justify;\">Cette initiative internationale poursuit plusieurs objectifs majeurs :<\/p>\n<ul style=\"text-align: justify;\">\n<li>renforcer l\u2019observation et la compr\u00e9hension de l\u2019oc\u00e9an ;<\/li>\n<li>am\u00e9liorer l\u2019acc\u00e8s aux donn\u00e9es scientifiques ;<\/li>\n<li>promouvoir une science collaborative et interdisciplinaire ;<\/li>\n<li>soutenir les politiques publiques et la prise de d\u00e9cision \u00e9clair\u00e9e ;<\/li>\n<li>favoriser des solutions concr\u00e8tes face aux d\u00e9fis climatiques et environnementaux.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Aujourd\u2019hui, la D\u00e9cennie de l\u2019Oc\u00e9an rassemble gouvernements, instituts de recherche, organisations internationales, entreprises et acteurs priv\u00e9s autour d\u2019une ambition commune : construire un oc\u00e9an plus r\u00e9silient, mieux prot\u00e9g\u00e9 et g\u00e9r\u00e9 de mani\u00e8re durable.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019int\u00e9gration du projet CLS au sein du programme JETZON illustre pleinement cette dynamique de coop\u00e9ration scientifique internationale.<\/strong><\/p>\n<p style=\"text-align: center; margin-top: 2em;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/86wZWu4UI6k?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>[\/vc_column_text][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h2>Renforcer les connaissances scientifiques pour mieux prot\u00e9ger l\u2019oc\u00e9an<\/h2>\n<p style=\"text-align: justify;\">L\u2019\u00e9tude de la biomasse des niveaux trophiques inf\u00e9rieurs et interm\u00e9diaires constitue un enjeu scientifique strat\u00e9gique pour am\u00e9liorer notre compr\u00e9hension du fonctionnement global des \u00e9cosyst\u00e8mes marins.<\/p>\n<p style=\"text-align: justify;\">Ces organismes, situ\u00e9s au c\u0153ur des r\u00e9seaux trophiques oc\u00e9aniques, jouent un r\u00f4le fondamental dans :<\/p>\n<ul>\n<li>la productivit\u00e9 biologique de l\u2019oc\u00e9an ;<\/li>\n<li>l\u2019\u00e9quilibre des ressources halieutiques, puisqu\u2019ils constituent une source de nourriture essentielle pour de nombreuses esp\u00e8ces commerciales ;<\/li>\n<li>le transfert du carbone des eaux de surface vers l\u2019oc\u00e9an profond ;<\/li>\n<li>la r\u00e9gulation du climat mondial.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Gr\u00e2ce aux technologies avanc\u00e9es d\u2019observation, aux donn\u00e9es satellitaires et aux analyses scientifiques, ce projet contribuera \u00e0 am\u00e9liorer la connaissance de m\u00e9canismes encore insuffisamment document\u00e9s aujourd\u2019hui.<\/strong><\/p>\n<p style=\"text-align: justify;\">Au-del\u00e0 de la recherche, ces travaux permettront \u00e9galement :<\/p>\n<ul>\n<li>de soutenir les politiques de conservation marine ;<\/li>\n<li>de contribuer \u00e0 une gestion durable des ressources oc\u00e9aniques ;<\/li>\n<li>de renforcer la coop\u00e9ration internationale en sciences oc\u00e9aniques gr\u00e2ce \u00e0 la mise \u00e0 disposition libre des donn\u00e9es produites et \u00e0 l\u2019organisation d\u2019ateliers scientifiques.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_btn title=\u00a0\u00bbContactez notre \u00e9quipe\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Ffisheries.groupcls.com%2Ffr%2Fcontact%2F|title:Contact|\u00a0\u00bb][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<h2>Une reconnaissance internationale qui confirme l\u2019engagement de CLS pour les sciences oc\u00e9aniques<\/h2>\n<p style=\"text-align: justify;\">Cette reconnaissance internationale marque une \u00e9tape importante pour CLS et ses partenaires dans leur engagement en faveur de l\u2019avancement des connaissances sur l\u2019oc\u00e9an.<\/p>\n<p style=\"text-align: justify;\">En rejoignant la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable et le programme JETZON, CLS contribue activement \u00e0 un effort scientifique mondial visant \u00e0 d\u00e9velopper les connaissances n\u00e9cessaires pour relever les grands d\u00e9fis climatiques, environnementaux et soci\u00e9taux.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c0 travers ce projet, CLS r\u00e9affirme son ambition de mettre la science, l\u2019innovation et les technologies d\u2019observation au service d\u2019un oc\u00e9an plus durable, plus r\u00e9silient et mieux prot\u00e9g\u00e9 pour les g\u00e9n\u00e9rations futures.<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Comprendre et pr\u00e9server l\u2019oc\u00e9an est devenu un enjeu scientifique, environnemental et soci\u00e9tal majeur.<\/p>\n","protected":false},"author":4,"featured_media":14796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[167],"class_list":["post-14754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-seapodym-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques - CLS Fisheries<\/title>\n<meta name=\"description\" content=\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques gr\u00e2ce \u00e0 son projet mondial sur le zooplancton et le micronecton.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques - CLS Fisheries\" \/>\n<meta property=\"og:description\" content=\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques gr\u00e2ce \u00e0 son projet mondial sur le zooplancton et le micronecton.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\" \/>\n<meta property=\"og:site_name\" content=\"CLS Fisheries\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-10T08:18:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T12:25:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CLS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CLS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\"},\"author\":{\"name\":\"CLS\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/person\/e6cbb173b0190a1b9d65ebadf7379fa2\"},\"headline\":\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable : une reconnaissance internationale au service de la science oc\u00e9anique\",\"datePublished\":\"2026-06-10T08:18:40+00:00\",\"dateModified\":\"2026-06-16T12:25:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\"},\"wordCount\":1456,\"publisher\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg\",\"keywords\":[\"Seapodym\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\",\"url\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\",\"name\":\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques - CLS Fisheries\",\"isPartOf\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg\",\"datePublished\":\"2026-06-10T08:18:40+00:00\",\"dateModified\":\"2026-06-16T12:25:39+00:00\",\"description\":\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques gr\u00e2ce \u00e0 son projet mondial sur le zooplancton et le micronecton.\",\"breadcrumb\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage\",\"url\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg\",\"contentUrl\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg\",\"width\":1024,\"height\":727,\"caption\":\"Krill\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fisheries.groupcls.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable : une reconnaissance internationale au service de la science oc\u00e9anique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#website\",\"url\":\"https:\/\/fisheries.groupcls.com\/fr\/\",\"name\":\"CLS Fisheries\",\"description\":\"CLS est cetifi\u00e9 par les grands organismes internationaux \u00e0 travers le monde et travaille d\u00e9j\u00e0 avec des milliers de navires de p\u00eache dans le monde entier.\",\"publisher\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fisheries.groupcls.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#organization\",\"name\":\"CLS\",\"url\":\"https:\/\/fisheries.groupcls.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png\",\"contentUrl\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png\",\"width\":107,\"height\":90,\"caption\":\"CLS\"},\"image\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/person\/e6cbb173b0190a1b9d65ebadf7379fa2\",\"name\":\"CLS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/437872ff04fcddb9081922fe55d21fec6aa6b660f2308ff296db2ecdf89ec5b1?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/437872ff04fcddb9081922fe55d21fec6aa6b660f2308ff296db2ecdf89ec5b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/437872ff04fcddb9081922fe55d21fec6aa6b660f2308ff296db2ecdf89ec5b1?s=96&d=mm&r=g\",\"caption\":\"CLS\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques - CLS Fisheries","description":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques gr\u00e2ce \u00e0 son projet mondial sur le zooplancton et le micronecton.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/","og_locale":"fr_FR","og_type":"article","og_title":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques - CLS Fisheries","og_description":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques gr\u00e2ce \u00e0 son projet mondial sur le zooplancton et le micronecton.","og_url":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/","og_site_name":"CLS Fisheries","article_published_time":"2026-06-10T08:18:40+00:00","article_modified_time":"2026-06-16T12:25:39+00:00","og_image":[{"width":1024,"height":727,"url":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg","type":"image\/jpeg"}],"author":"CLS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CLS","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#article","isPartOf":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/"},"author":{"name":"CLS","@id":"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/person\/e6cbb173b0190a1b9d65ebadf7379fa2"},"headline":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable : une reconnaissance internationale au service de la science oc\u00e9anique","datePublished":"2026-06-10T08:18:40+00:00","dateModified":"2026-06-16T12:25:39+00:00","mainEntityOfPage":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/"},"wordCount":1456,"publisher":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#organization"},"image":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage"},"thumbnailUrl":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg","keywords":["Seapodym"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/","url":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/","name":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques - CLS Fisheries","isPartOf":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage"},"image":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage"},"thumbnailUrl":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg","datePublished":"2026-06-10T08:18:40+00:00","dateModified":"2026-06-16T12:25:39+00:00","description":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques gr\u00e2ce \u00e0 son projet mondial sur le zooplancton et le micronecton.","breadcrumb":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#primaryimage","url":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg","contentUrl":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2026\/06\/Krill.jpg","width":1024,"height":727,"caption":"Krill"},{"@type":"BreadcrumbList","@id":"https:\/\/fisheries.groupcls.com\/fr\/cls-rejoint-decennie-des-nations-unies-pour-sciences-oceaniques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fisheries.groupcls.com\/fr\/"},{"@type":"ListItem","position":2,"name":"CLS rejoint la D\u00e9cennie des Nations Unies pour les sciences oc\u00e9aniques au service du d\u00e9veloppement durable : une reconnaissance internationale au service de la science oc\u00e9anique"}]},{"@type":"WebSite","@id":"https:\/\/fisheries.groupcls.com\/fr\/#website","url":"https:\/\/fisheries.groupcls.com\/fr\/","name":"CLS Fisheries","description":"CLS est cetifi\u00e9 par les grands organismes internationaux \u00e0 travers le monde et travaille d\u00e9j\u00e0 avec des milliers de navires de p\u00eache dans le monde entier.","publisher":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fisheries.groupcls.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fisheries.groupcls.com\/fr\/#organization","name":"CLS","url":"https:\/\/fisheries.groupcls.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png","contentUrl":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png","width":107,"height":90,"caption":"CLS"},"image":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/person\/e6cbb173b0190a1b9d65ebadf7379fa2","name":"CLS","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/437872ff04fcddb9081922fe55d21fec6aa6b660f2308ff296db2ecdf89ec5b1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/437872ff04fcddb9081922fe55d21fec6aa6b660f2308ff296db2ecdf89ec5b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/437872ff04fcddb9081922fe55d21fec6aa6b660f2308ff296db2ecdf89ec5b1?s=96&d=mm&r=g","caption":"CLS"}}]}},"_links":{"self":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/posts\/14754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/comments?post=14754"}],"version-history":[{"count":20,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/posts\/14754\/revisions"}],"predecessor-version":[{"id":14819,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/posts\/14754\/revisions\/14819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/media\/14796"}],"wp:attachment":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/media?parent=14754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/categories?post=14754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/tags?post=14754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}