{"id":9968,"date":"2018-11-16T11:54:42","date_gmt":"2018-11-16T10:54:42","guid":{"rendered":"https:\/\/fisheries.groupcls.com\/general-conditions-of-use\/"},"modified":"2026-01-22T11:19:07","modified_gmt":"2026-01-22T10:19:07","slug":"conditions-generales-d-utilisation","status":"publish","type":"page","link":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales d&rsquo;utilisation"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales d\u2019Utilisation (ci-apr\u00e8s les \u00ab CGU \u00bb) ont pour objet de d\u00e9finir les modalit\u00e9s d\u2019acc\u00e8s et les conditions d\u2019utilisation du site <a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). En utilisant\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>, vous reconnaissez avoir pris connaissance des pr\u00e9sentes CGU, et d\u2019en accepter les termes sans r\u00e9serve.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Mentions l\u00e9gales<\/strong><\/h2>\n<p>Le Site est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 CLS, Soci\u00e9t\u00e9 par Actions Simplifi\u00e9e au capital de 75.440.501,01 euros et dont le si\u00e8ge social est situ\u00e9 11 rue Herm\u00e8s, Parc Technologique du Canal, 31520 Ramonville-Saint-Agne, identifi\u00e9e sous le num\u00e9ro 338 034 390 RCS TOULOUSE, joignable par t\u00e9l\u00e9phone au T\u00e9l\u00e9phone : (33) 05 61 39 47 00, et par Fax au (33) 05 61 75 10 14 (ci-apr\u00e8s \u00ab CLS \u00bb).<\/p>\n<p>Le directeur de la publication est St\u00e9phanie LIMOUZIN, Pr\u00e9sidente de CLS.<\/p>\n<p>Le Site est h\u00e9berg\u00e9 par CLS.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Pr\u00e9sentation<\/strong><\/h2>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">Fisheries.groupcls.com<\/a>\u00a0est un site destin\u00e9 \u00e0 la communication de CLS. Il permet aux internautes d\u2019acc\u00e9der aux\u00a0informations sur supports num\u00e9riques de diffusion qui transmettent les id\u00e9es et actions mises en place par la Soci\u00e9t\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Port\u00e9e du contenu<\/strong><\/h2>\n<p style=\"text-align: justify;\">CLS se r\u00e9serve le droit de modifier \u00e0 tout moment le contenu du pr\u00e9sent site sans pr\u00e9avis et, notamment, son offre commerciale et ses conditions g\u00e9n\u00e9rales de fourniture.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Acc\u00e8s et utilisation<\/strong><\/h2>\n<p style=\"text-align: justify;\">1) Le site\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>\u00a0est libre d\u2019acc\u00e8s\u00a0mais demande une inscription pr\u00e9alable pour acc\u00e9der \u00e0 certains contenus.<\/p>\n<p style=\"text-align: justify;\">2) Les publications post\u00e9es sur les comptes Facebook,\u00a0Twitter, LinkedIn et YouTube sont aussi diffus\u00e9es sur le site\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>. En utilisant\u00a0le site <a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>\u00a0vous vous engagez \u00e0 ce qu\u2019aucun message que vous envoyez via le site ainsi que sur les comptes Facebook,\u00a0Twitter, LinkedIn et YouTube de CLS :<\/p>\n<ul style=\"text-align: justify;\">\n<li>ne porte atteinte \u00e0 l\u2019ordre public et aux bonnes m\u0153urs,<\/li>\n<li>ne fasse l\u2019apologie de crimes contre l\u2019humanit\u00e9,<\/li>\n<li>n\u2019incite \u00e0 la haine raciale,<\/li>\n<li>n\u2019incite \u00e0 la discrimination, la haine d\u2019une personne ou d\u2019un groupe de personnes en Raison de leur origine ou de leur appartenance ou de leur non appartenance \u00e0 une ethnie, une nation, une race ou une religion d\u00e9termin\u00e9e,<\/li>\n<li>ne menace une personne ou un groupe de personnes,<\/li>\n<li>n\u2019aie un caract\u00e8re injurieux, diffamatoire, raciste, x\u00e9nophobe, r\u00e9visionniste ou portant atteinte \u00e0 l\u2019honneur ou \u00e0 la r\u00e9putation d\u2019autrui,<\/li>\n<li>n\u2019aie un caract\u00e8re pornographique ou p\u00e9dophile,<\/li>\n<li>n\u2019incite \u00e0 commettre un d\u00e9lit, un crime ou un acte de terrorisme ou faisant l\u2019apologie des crimes de guerre ou des crimes contre l\u2019humanit\u00e9,<\/li>\n<li>n\u2019incite au suicide,<\/li>\n<li>n\u2019aie un caract\u00e8re commercial ou publicitaire, ou faisant appel \u00e0 des dons ou des financements,<\/li>\n<li>ne viole le caract\u00e8re priv\u00e9 des correspondances,<\/li>\n<li>ne porte atteinte directement ou indirectement \u00e0 l\u2019image de\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>\u00a0et plus largement \u00e0 celle de CLS, propri\u00e9taire du site, et du Groupe CLS,<\/li>\n<li>ne porte atteinte au respect de la vie priv\u00e9e des personnes et de leur droit \u00e0 l\u2019image.<\/li>\n<li>et de mani\u00e8re plus g\u00e9n\u00e9rale ne contrevient \u00e0 aucune disposition l\u00e9gale ou r\u00e9glementaire.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">3) A ce titre, votre responsabilit\u00e9 personnelle pourra \u00eatre engag\u00e9e, du fait de vos propos et des propos illicites qu\u2019ils auraient engendr\u00e9. Toute mesure de sauvegarde pourra \u00eatre prise par l\u2019\u00e9diteur du site.<\/p>\n<p style=\"text-align: justify;\">4) Afin de contribuer \u00e0 la d\u00e9fense des valeurs de\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>, nous vous incitons \u00e0 signaler les contenus, qui seraient contraires aux bonnes m\u0153urs et \u00e0 l\u2019ordre public que nous avons \u00e9nonc\u00e9s ci-dessus, ainsi que les contenus qui porteraient atteinte aux droits d\u2019une tierce personne. Pour ce faire, envoyez-nous un mail \u00e0 &#x6c;\u2019a&#x64;&#x72;&#x65;&#115;se\u00a0&#100;&#112;o&#x40;&#x67;&#x72;&#111;up&#x63;&#x6c;&#115;&#46;c&#x6f;&#x6d;.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Liens hypertextes<\/strong><\/h2>\n<ol style=\"text-align: justify;\">\n<li>Ce Site peut contenir des liens avec des sites de tiers. Ces liens sont fournis aux seules fins de commodit\u00e9s et l\u2019inclusion de ces liens n\u2019implique en aucune fa\u00e7on un contr\u00f4le des \u00e9l\u00e9ments des sites auxquels les liens donnent acc\u00e8s ni un quelconque aval \u00e0, ni une quelconque garantie sur, ces \u00e9l\u00e9ments. L\u2019acc\u00e8s \u00e0 ces sites est de la seule responsabilit\u00e9 de l\u2019utilisateur.<\/li>\n<li>Transmission des informations par les utilisateurs\n<ul>\n<li>Toute information ou demande d\u2019information que vous pourriez adresser \u00e0 CLS via le site ou via la messagerie \u00e9lectronique \u00e0 laquelle le site peut donner acc\u00e8s, est consid\u00e9r\u00e9e comme non confidentielle.<\/li>\n<li>Vous pouvez \u00e9galement adresser vos informations ou demandes par courrier \u00e0 l\u2019adresse du si\u00e8ge social de CLS \u00e0 l\u2019attention du d\u00e9partement identifi\u00e9 dans la partie correspondante de ce site.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Mod\u00e9ration<\/strong><\/h2>\n<p style=\"text-align: justify;\">Vous acceptez que vos contributions, quelques soient leurs supports et leurs natures, soient mod\u00e9r\u00e9es, c\u2019est-\u00e0-dire lues, supprim\u00e9es dans le cas o\u00f9 elles ne respectent pas les pr\u00e9sentes CGU.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Suspension et r\u00e9siliation<\/strong><\/h2>\n<ol style=\"text-align: justify;\">\n<li>En cas :\n<ul>\n<li>d\u2019utilisation non conforme des services et fonctionnalit\u00e9s de\u00a0CLS,<\/li>\n<li>de manquement aux dispositions de ces CGU quant aux messages post\u00e9s sur les\u00a0pages Facebook,\u00a0LinkedIn et\u00a0Twitter et la cha\u00eene YouTube de CLS, votre acc\u00e8s \u00e0\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a> pourra \u00eatre suspendu sans aucun pr\u00e9avis. Les comptes cr\u00e9\u00e9s pour remplacer les comptes suspendus seront \u00e9galement suspendus.<\/li>\n<\/ul>\n<\/li>\n<li>Votre inscription sera alors d\u00e9sactiv\u00e9e. Vous serez inform\u00e9(e)s de cette d\u00e9sactivation par un message envoy\u00e9 \u00e0 votre adresse email. Votre inscription sera r\u00e9activ\u00e9e, au moment o\u00f9 vous aurez proc\u00e9d\u00e9 aux modifications n\u00e9cessaires pour vous mettre en conformit\u00e9 avec les CGU que vous avez accept\u00e9es.<\/li>\n<li>Votre \u00eates d\u00e9finitivement d\u00e9sinscrits lorsque, pendant la p\u00e9riode de suspension, le manquement aux CGU n\u2019a pas \u00e9t\u00e9 r\u00e9par\u00e9 dans un d\u00e9lai de quinze (15) jours suivant notification de votre d\u00e9sinscription par e-mail \u00e0 l\u2019adresse renseign\u00e9e lors de votre inscription.<\/li>\n<li>Par ailleurs, il pourra \u00eatre mis fin \u00e0 tout moment \u00e0 votre inscription, moyennant le respect d\u2019un pr\u00e9avis raisonnable. Un e-mail vous sera envoy\u00e9 \u00e0 votre adresse pour vous notifier la d\u00e9sinscription et le pr\u00e9avis.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Droits d\u2019auteur, marques et autres droits de propri\u00e9t\u00e9 intellectuelle<\/strong><\/h2>\n<ol style=\"text-align: justify;\">\n<li>Ce site et son contenu sont prot\u00e9g\u00e9s par le droit d\u2019auteur et\/ou autres droits de propri\u00e9t\u00e9 intellectuelle qui sont la propri\u00e9t\u00e9 de CLS ou de tiers.<\/li>\n<li>La reproduction et l\u2019utilisation des \u00e9l\u00e9ments de ce site (et de toute information qui y est incorpor\u00e9e telle que, sans limitation, les articles, les images graphiques, les photographies, diagrammes, enregistrements vid\u00e9os\u2026) sont autoris\u00e9es sous r\u00e9serve que\u00a0:\n<ul>\n<li>Cette reproduction et son utilisation soient strictement pour information, \u00e0 des fins non commerciales \u00e0 l\u2019int\u00e9rieur de votre organisation pour vous permettre de mieux conna\u00eetre CLS ; et,<\/li>\n<li>les \u00e9l\u00e9ments et informations ne soient pas modifi\u00e9s en tout ou partie et de quelque mani\u00e8re que ce soit.<\/li>\n<li>tout autre droit de reproduction et\/ou d\u2019utilisation est express\u00e9ment interdit.<\/li>\n<\/ul>\n<\/li>\n<li>En outre, certains noms cit\u00e9s peuvent \u00eatre prot\u00e9g\u00e9s par des marques qui sont la propri\u00e9t\u00e9 de CLS ou de tiers sans que la mention de cette protection ne soit n\u00e9cessairement indiqu\u00e9e.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Protection des donn\u00e9es personnelles<\/strong><\/h2>\n<p style=\"text-align: justify;\">1. Les informations recueillies (par exemple, le nombre de pages vues, le nombre de visites, ainsi que l\u2019activit\u00e9 des visiteurs sur le site, et leur fr\u00e9quence de retour) font l\u2019objet d\u2019un traitement informatique destin\u00e9 \u00e0 l\u2019analyse des visites.<\/p>\n<p style=\"text-align: justify;\">2. Conform\u00e9ment au R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l\u2019\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es dit \u00ab RGPD \u00bb et \u00e0 la loi \u00ab informatique et libert\u00e9s \u00bb du 6 janvier 1978 modifi\u00e9e en 2004 et \u00e0 la directive europ\u00e9enne du 24 octobre 1995, vous b\u00e9n\u00e9ficiez d\u2019un droit d\u2019acc\u00e8s et de rectification aux informations qui vous concernent, que vous pouvez exercer en vous adressant \u00e0 notre DPO (Data Protection Officer) \u00e0 l\u2019adresse suivante :\u00a0&#x64;&#112;&#x6f;&#x40;g&#x72;&#111;&#x75;&#x70;c&#x6c;&#115;&#x2e;&#x63;o&#x6d;.<\/p>\n<p style=\"text-align: justify;\">3. De plus ce Site s\u2019aligne sur la Politique de protection des donn\u00e9es personnelles du Groupe CLS dont vous trouverez le contenu int\u00e9gral en cliquant\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/politique-de-protection-des-donnees-personnelles\/\">ici<\/a>.<\/p>\n<p style=\"text-align: justify;\">4. Chaque formulaire ou service web limite la collecte des donn\u00e9es personnelles au strict n\u00e9cessaire et tout profilage automatique est proscrit. Nous garantissons l\u2019intervention d\u2019un humain dans toute d\u00e9cision vous concernant.<\/p>\n<p style=\"text-align: justify;\">En tout \u00e9tat de cause, il vous est possible d\u2019exercer, aupr\u00e8s de notre\u00a0<em>Data Protection Officer<\/em>, votre droit de\u00a0:<\/p>\n<ul style=\"text-align: justify;\">\n<li>d\u2019information<\/li>\n<li>d\u2019effacement<\/li>\n<li>d\u2019opposition \u00e0 figurer dans un fichier et \u00e0 ce que les donn\u00e9es vous concernant soient diffus\u00e9es, transmises ou conserv\u00e9es (pour des motifs l\u00e9gitimes et qui n\u2019entraverait pas le fonctionnement du site ou du service demand\u00e9)<\/li>\n<li>v\u00e9rification de vos donn\u00e9es par l\u2019exercice de votre droit d\u2019acc\u00e8s<\/li>\n<li>de rectification de vos donn\u00e9es inexactes<\/li>\n<li>de d\u00e9r\u00e9f\u00e9rencement d\u2019un contenu et ne plus associer vos nom\/pr\u00e9nom \u00e0 un contenu visible dans un moteur de recherche (droit \u00e0 l\u2019oubli)<\/li>\n<li>d\u2019exiger une copie de vos donn\u00e9es<\/li>\n<li>de demander l\u2019arr\u00eat de l\u2019utilisation de vos donn\u00e9es (pour des motifs l\u00e9gitimes et qui n\u2019entraverait pas le fonctionnement du site ou du service demand\u00e9)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">5. Les donn\u00e9es personnelles recueillies dans le cadre des services propos\u00e9s sur\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>\u00a0sont trait\u00e9es selon des protocoles s\u00e9curis\u00e9s et permettent \u00e0 CLS de g\u00e9rer les demandes re\u00e7ues dans ses applications informatiques.<\/p>\n<p style=\"text-align: justify;\">6. Pour toute information ou exercice de vos droits sur les traitements de donn\u00e9es personnelles r\u00e9alis\u00e9s par CLS, vous pouvez \u00e9galement contacter notre DPO par courrier sign\u00e9 et accompagn\u00e9 de la copie d\u2019un titre d\u2019identit\u00e9 \u00e0 l\u2019adresse suivante :<\/p>\n<p style=\"text-align: center;\"><strong>COLLECTE LOCALISATION SATELLITES<br \/>\n<\/strong>Louis CONTE \u2013 DPO<br \/>\n11 rue Herm\u00e8s<br \/>\nParc Technologique du Canal<br \/>\n31520 Ramonville-Saint-Agne<\/p>\n<p style=\"text-align: justify;\">7. Vous trouverez le R\u00e8glement (UE) relative \u00e0 la protection des personnes physiques \u00e0 l\u2019\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es dit \u00ab RGPD \u00bb et la loi \u00ab informatique et libert\u00e9s \u00bb sur le site de la Commission Nationale de l\u2019Informatique et des Libert\u00e9s, \u00e0 l\u2019adresse suivante :\u00a0<a href=\"https:\/\/www.cnil.fr\/\">https:\/\/www.cnil.fr<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>Exclusions de garantie et de responsabilit\u00e9<\/strong><\/h2>\n<ol style=\"text-align: justify;\">\n<li>CLS s\u2019efforce de fournir sur ce site des informations exactes et actualis\u00e9es.<\/li>\n<li>Cependant, CLS ne garantit en aucun cas l\u2019exhaustivit\u00e9 de ces informations et d\u00e9cline toute responsabilit\u00e9 en cas d\u2019erreurs ou d\u2019omissions, de m\u00eame qu\u2019en cas de modification du contenu qui serait due \u00e0 l\u2019intrusion d\u2019un virus du fait d\u2019un tiers.<\/li>\n<li>Les \u00e9l\u00e9ments de ce site sont fournis \u00e0 titre d\u2019information g\u00e9n\u00e9rale seulement et ne peuvent servir de base \u00e0 une quelconque transaction. En particulier, s\u2019agissant des informations financi\u00e8res qui peuvent \u00eatre fournies sur ce site.<\/li>\n<li>Toutes les informations ou l\u2019une quelconque d\u2019entre elles publi\u00e9es sur ce site sont fournies en l\u2019\u00e9tat sans garantie d\u2019aucune sorte, expresse ou implicite, qu\u2019il s\u2019agisse, et sans que cela soit limitatif, de garantie de qualit\u00e9 loyale et marchande, d\u2019ad\u00e9quation \u00e0 un besoin sp\u00e9cifique ou d\u2019absence de contrefa\u00e7on de droits de tiers.<\/li>\n<li>CLS n\u2019apporte aucune garantie quant \u00e0 l\u2019exactitude et au caract\u00e8re complet des \u00e9l\u00e9ments et\/ou des informations publi\u00e9es sur ce site.<\/li>\n<li>CLS ne garantit en aucune mani\u00e8re un acc\u00e8s ininterrompu \u00e0 ce site ainsi que la s\u00e9curit\u00e9 du site et l\u2019absence de tous virus ou autres h\u00f4tes ind\u00e9sirables (y compris dans les \u00e9l\u00e9ments du site et dans les informations qui y sont incorpor\u00e9es).<\/li>\n<li>L\u2019utilisation des \u00e9l\u00e9ments du site et de toute information qui y est incluse ainsi que l\u2019acc\u00e8s \u00e0 ce site sont de la seule responsabilit\u00e9 de l\u2019utilisateur. CLS d\u00e9gage sa responsabilit\u00e9 pour quelque dommage que ce soit, ceci incluant sans limitation les dommages directs et indirects qui pourraient r\u00e9sulter de l\u2019acc\u00e8s \u00e0 ce site et de l\u2019utilisation en tout ou partie des \u00e9l\u00e9ments ou informations qui y sont contenus.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><strong>R\u00e8glement amiable et diff\u00e9rend<\/strong><\/h2>\n<p style=\"text-align: justify;\">En cas de difficult\u00e9s survenant au cours de votre utilisation de\u00a0<a href=\"https:\/\/fisheries.groupcls.com\/fr\/\">fisheries.groupcls.com<\/a>\u00a0ou au sujet des pr\u00e9sentes CGU, vous vous engagez \u00e0 rechercher une solution amiable avec l\u2019\u00e9diteur du site. A ce titre, vous vous engagez \u00e0 mettre en \u0153uvre cette conciliation avant l\u2019exercice de toute voie de recours.<\/p>\n<p style=\"text-align: justify;\">Les pr\u00e9sentes CGU sont r\u00e9gies par la loi fran\u00e7aise pour toutes difficult\u00e9s relatives \u00e0 leur appr\u00e9ciation, \u00e0 leur validit\u00e9 et \u00e0 leur ex\u00e9cution. Les juridictions fran\u00e7aises sont seules comp\u00e9tentes pour conna\u00eetre de tout diff\u00e9rend relatif \u00e0 l\u2019application et l\u2019interpr\u00e9tation de ces CGU.<\/p>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_btn title=\u00a0\u00bbPolitique de protection des donn\u00e9es personnelles\u00a0\u00bb color=\u00a0\u00bbprimary\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Ffisheries.groupcls.com%2Ffr%2Fpolitique-de-protection-des-donnees-personnelles%2F|||\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_btn title=\u00a0\u00bbGestion des cookies\u00a0\u00bb color=\u00a0\u00bbprimary\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb link=\u00a0\u00bburl:https%3A%2F%2Ffisheries.groupcls.com%2Ffr%2Fgestion-des-cookies%2F|||\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb] Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales d\u2019Utilisation (ci-apr\u00e8s les \u00ab CGU \u00bb) ont pour objet de d\u00e9finir les modalit\u00e9s d\u2019acc\u00e8s et les conditions d\u2019utilisation du site fisheries.groupcls.com\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). En utilisant\u00a0fisheries.groupcls.com, vous reconnaissez avoir pris connaissance des pr\u00e9sentes CGU, et d\u2019en accepter les termes sans r\u00e9serve. &nbsp; Mentions l\u00e9gales Le Site est \u00e9dit\u00e9<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":148,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9968","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions g\u00e9n\u00e9rales d&#039;utilisation - CLS Fisheries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions g\u00e9n\u00e9rales d&#039;utilisation - CLS Fisheries\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb] Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales d\u2019Utilisation (ci-apr\u00e8s les \u00ab CGU \u00bb) ont pour objet de d\u00e9finir les modalit\u00e9s d\u2019acc\u00e8s et les conditions d\u2019utilisation du site fisheries.groupcls.com\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). En utilisant\u00a0fisheries.groupcls.com, vous reconnaissez avoir pris connaissance des pr\u00e9sentes CGU, et d\u2019en accepter les termes sans r\u00e9serve. &nbsp; Mentions l\u00e9gales Le Site est \u00e9dit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/\" \/>\n<meta property=\"og:site_name\" content=\"CLS Fisheries\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T10:19:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/\",\"url\":\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/\",\"name\":\"Conditions g\u00e9n\u00e9rales d'utilisation - CLS Fisheries\",\"isPartOf\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#website\"},\"datePublished\":\"2018-11-16T10:54:42+00:00\",\"dateModified\":\"2026-01-22T10:19:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fisheries.groupcls.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions g\u00e9n\u00e9rales d&#8217;utilisation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#website\",\"url\":\"https:\/\/fisheries.groupcls.com\/fr\/\",\"name\":\"CLS Fisheries\",\"description\":\"CLS est cetifi\u00e9 par les grands organismes internationaux \u00e0 travers le monde et travaille d\u00e9j\u00e0 avec des milliers de navires de p\u00eache dans le monde entier.\",\"publisher\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fisheries.groupcls.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#organization\",\"name\":\"CLS\",\"url\":\"https:\/\/fisheries.groupcls.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png\",\"contentUrl\":\"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png\",\"width\":107,\"height\":90,\"caption\":\"CLS\"},\"image\":{\"@id\":\"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales d'utilisation - CLS Fisheries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions g\u00e9n\u00e9rales d'utilisation - CLS Fisheries","og_description":"[vc_row][vc_column][vc_column_text css=\u00a0\u00bb\u00a0\u00bb] Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales d\u2019Utilisation (ci-apr\u00e8s les \u00ab CGU \u00bb) ont pour objet de d\u00e9finir les modalit\u00e9s d\u2019acc\u00e8s et les conditions d\u2019utilisation du site fisheries.groupcls.com\u00a0(ci-apr\u00e8s le \u00ab Site \u00bb). En utilisant\u00a0fisheries.groupcls.com, vous reconnaissez avoir pris connaissance des pr\u00e9sentes CGU, et d\u2019en accepter les termes sans r\u00e9serve. &nbsp; Mentions l\u00e9gales Le Site est \u00e9dit\u00e9","og_url":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/","og_site_name":"CLS Fisheries","article_modified_time":"2026-01-22T10:19:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/","url":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/","name":"Conditions g\u00e9n\u00e9rales d'utilisation - CLS Fisheries","isPartOf":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#website"},"datePublished":"2018-11-16T10:54:42+00:00","dateModified":"2026-01-22T10:19:07+00:00","breadcrumb":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fisheries.groupcls.com\/fr\/conditions-generales-d-utilisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fisheries.groupcls.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Conditions g\u00e9n\u00e9rales d&#8217;utilisation"}]},{"@type":"WebSite","@id":"https:\/\/fisheries.groupcls.com\/fr\/#website","url":"https:\/\/fisheries.groupcls.com\/fr\/","name":"CLS Fisheries","description":"CLS est cetifi\u00e9 par les grands organismes internationaux \u00e0 travers le monde et travaille d\u00e9j\u00e0 avec des milliers de navires de p\u00eache dans le monde entier.","publisher":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fisheries.groupcls.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fisheries.groupcls.com\/fr\/#organization","name":"CLS","url":"https:\/\/fisheries.groupcls.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png","contentUrl":"https:\/\/fisheries.groupcls.com\/wp-content\/uploads\/2016\/04\/logo-cls.png","width":107,"height":90,"caption":"CLS"},"image":{"@id":"https:\/\/fisheries.groupcls.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/pages\/9968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/comments?post=9968"}],"version-history":[{"count":10,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/pages\/9968\/revisions"}],"predecessor-version":[{"id":13844,"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/pages\/9968\/revisions\/13844"}],"wp:attachment":[{"href":"https:\/\/fisheries.groupcls.com\/fr\/wp-json\/wp\/v2\/media?parent=9968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}